{"id":3001,"date":"2026-02-07T20:48:25","date_gmt":"2026-02-08T01:48:25","guid":{"rendered":"http:\/\/gospelbarn.com\/?post_type=tribe_events&#038;p=3001"},"modified":"2026-02-07T20:48:25","modified_gmt":"2026-02-08T01:48:25","slug":"down-east-boys-6","status":"publish","type":"tribe_events","link":"http:\/\/gospelbarn.com\/index.php\/schedule\/down-east-boys-6\/","title":{"rendered":"Down East Boys"},"content":{"rendered":"<p>May 30- <a href=\"http:\/\/DownEastBoys.com\">Down East Boys<\/a> from Reidsville, North Carolina<\/p>\n<p>Concert begins at 6pm<\/p>\n<p>Auditorium Doors open at 430pm<\/p>\n<p>Tickets:\u00a0 $8 \u2013 Available at the door beginning at 430pm<\/p>\n<p>Children ages 12 & under are FREE<\/p>\n<p>Love Offering for Down East Boys<\/p>\n","protected":false},"excerpt":{"rendered":"<p>May 30- Down East Boys from Reidsville, North Carolina Concert begins at 6pm Auditorium Doors open at 430pm Tickets:\u00a0 $8 \u2013 Available at the door beginning at 430pm Children ages 12 &#038; under are FREE Love Offering for Down East Boys<\/p>\n","protected":false},"author":1,"featured_media":3002,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-3001","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"http:\/\/gospelbarn.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/3001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/gospelbarn.com\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"http:\/\/gospelbarn.com\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"http:\/\/gospelbarn.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"http:\/\/gospelbarn.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/3001\/revisions"}],"predecessor-version":[{"id":3003,"href":"http:\/\/gospelbarn.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/3001\/revisions\/3003"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/gospelbarn.com\/index.php\/wp-json\/wp\/v2\/media\/3002"}],"wp:attachment":[{"href":"http:\/\/gospelbarn.com\/index.php\/wp-json\/wp\/v2\/media?parent=3001"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/gospelbarn.com\/index.php\/wp-json\/wp\/v2\/tags?post=3001"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"http:\/\/gospelbarn.com\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=3001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}